{"id":35034,"date":"2024-09-18T17:40:27","date_gmt":"2024-09-18T15:40:27","guid":{"rendered":"https:\/\/fondazionefeltrinelli.it\/?page_id=35034"},"modified":"2024-09-18T17:40:27","modified_gmt":"2024-09-18T15:40:27","slug":"about-us-2","status":"publish","type":"page","link":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/","title":{"rendered":"About us"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":35154,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-35034","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About us - Fondazione Giangiacomo Feltrinelli<\/title>\n<meta name=\"description\" content=\"About us: discover Giangiacomo Feltrinelli Foundation, from our founder, archive and library to innovative headquarters in Milan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About us - Fondazione Giangiacomo Feltrinelli\" \/>\n<meta property=\"og:description\" content=\"About us: discover Giangiacomo Feltrinelli Foundation, from our founder, archive and library to innovative headquarters in Milan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Giangiacomo Feltrinelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FondazioneFeltrinelli\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2024\/09\/Ok_europe__-1024x471.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2024\/09\/Ok_europe__.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@FondFeltrinelli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/about-us-2\\\/\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/about-us-2\\\/\",\"name\":\"About us - Fondazione Giangiacomo Feltrinelli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/about-us-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/about-us-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ok_europe__.jpg\",\"datePublished\":\"2024-09-18T15:40:27+00:00\",\"description\":\"About us: discover Giangiacomo Feltrinelli Foundation, from our founder, archive and library to innovative headquarters in Milan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/about-us-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/about-us-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/about-us-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ok_europe__.jpg\",\"contentUrl\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ok_europe__.jpg\",\"width\":1920,\"height\":883},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/about-us-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#website\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/\",\"name\":\"Fondazione Giangiacomo Feltrinelli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#organization\",\"name\":\"Fondazione Giangiacomo Feltrinelli\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-Fondazione-Feltrinelli-2.jpg\",\"contentUrl\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-Fondazione-Feltrinelli-2.jpg\",\"width\":632,\"height\":552,\"caption\":\"Fondazione Giangiacomo Feltrinelli\"},\"image\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FondazioneFeltrinelli\",\"https:\\\/\\\/x.com\\\/FondFeltrinelli\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqUC9dAHm8G3edg2GPEoNow\",\"https:\\\/\\\/www.instagram.com\\\/fondazionefeltrinelli\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company-beta\\\/9183434\\\/?pathWildcard=9183434\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About us - Fondazione Giangiacomo Feltrinelli","description":"About us: discover Giangiacomo Feltrinelli Foundation, from our founder, archive and library to innovative headquarters in Milan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/","og_locale":"en_US","og_type":"article","og_title":"About us - Fondazione Giangiacomo Feltrinelli","og_description":"About us: discover Giangiacomo Feltrinelli Foundation, from our founder, archive and library to innovative headquarters in Milan.","og_url":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/","og_site_name":"Fondazione Giangiacomo Feltrinelli","article_publisher":"https:\/\/www.facebook.com\/FondazioneFeltrinelli","og_image":[{"url":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2024\/09\/Ok_europe__-1024x471.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2024\/09\/Ok_europe__.jpg","twitter_site":"@FondFeltrinelli","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/","url":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/","name":"About us - Fondazione Giangiacomo Feltrinelli","isPartOf":{"@id":"https:\/\/fondazionefeltrinelli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/#primaryimage"},"image":{"@id":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2024\/09\/Ok_europe__.jpg","datePublished":"2024-09-18T15:40:27+00:00","description":"About us: discover Giangiacomo Feltrinelli Foundation, from our founder, archive and library to innovative headquarters in Milan.","breadcrumb":{"@id":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/#primaryimage","url":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2024\/09\/Ok_europe__.jpg","contentUrl":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2024\/09\/Ok_europe__.jpg","width":1920,"height":883},{"@type":"BreadcrumbList","@id":"https:\/\/fondazionefeltrinelli.it\/en\/about-us-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fondazionefeltrinelli.it\/en\/"},{"@type":"ListItem","position":2,"name":"About us"}]},{"@type":"WebSite","@id":"https:\/\/fondazionefeltrinelli.it\/#website","url":"https:\/\/fondazionefeltrinelli.it\/","name":"Fondazione Giangiacomo Feltrinelli","description":"","publisher":{"@id":"https:\/\/fondazionefeltrinelli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondazionefeltrinelli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fondazionefeltrinelli.it\/#organization","name":"Fondazione Giangiacomo Feltrinelli","url":"https:\/\/fondazionefeltrinelli.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fondazionefeltrinelli.it\/#\/schema\/logo\/image\/","url":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/05\/Logo-Fondazione-Feltrinelli-2.jpg","contentUrl":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/05\/Logo-Fondazione-Feltrinelli-2.jpg","width":632,"height":552,"caption":"Fondazione Giangiacomo Feltrinelli"},"image":{"@id":"https:\/\/fondazionefeltrinelli.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FondazioneFeltrinelli","https:\/\/x.com\/FondFeltrinelli","https:\/\/www.youtube.com\/channel\/UCqUC9dAHm8G3edg2GPEoNow","https:\/\/www.instagram.com\/fondazionefeltrinelli\/","https:\/\/www.linkedin.com\/company-beta\/9183434\/?pathWildcard=9183434"]}]}},"_links":{"self":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/35034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/comments?post=35034"}],"version-history":[{"count":1,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/35034\/revisions"}],"predecessor-version":[{"id":35139,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/35034\/revisions\/35139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/media\/35154"}],"wp:attachment":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/media?parent=35034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}