{"id":24126,"date":"2023-05-04T13:48:52","date_gmt":"2023-05-04T11:48:52","guid":{"rendered":"https:\/\/fondazionefeltrinelli.it\/?page_id=24126"},"modified":"2024-09-19T11:18:43","modified_gmt":"2024-09-19T09:18:43","slug":"homepage","status":"publish","type":"page","link":"https:\/\/fondazionefeltrinelli.it\/en\/","title":{"rendered":"Homepage"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-24126","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fondazione Giangiacomo Feltrinelli<\/title>\n<meta name=\"description\" content=\"Fondazione Giangiacomo Feltrinelli is one of the most important european research and culture centers in history, politics, economy and more\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondazionefeltrinelli.it\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fondazione Giangiacomo Feltrinelli\" \/>\n<meta property=\"og:description\" content=\"Fondazione Giangiacomo Feltrinelli is one of the most important european research and culture centers in history, politics, economy and more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondazionefeltrinelli.it\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Giangiacomo Feltrinelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FondazioneFeltrinelli\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T09:18:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/05\/Logo-Fondazione-Feltrinelli-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FondFeltrinelli\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/\",\"name\":\"Fondazione Giangiacomo Feltrinelli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#website\"},\"datePublished\":\"2023-05-04T11:48:52+00:00\",\"dateModified\":\"2024-09-19T09:18:43+00:00\",\"description\":\"Fondazione Giangiacomo Feltrinelli is one of the most important european research and culture centers in history, politics, economy and more\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#website\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/\",\"name\":\"Fondazione Giangiacomo Feltrinelli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#organization\",\"name\":\"Fondazione Giangiacomo Feltrinelli\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-Fondazione-Feltrinelli-2.jpg\",\"contentUrl\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-Fondazione-Feltrinelli-2.jpg\",\"width\":632,\"height\":552,\"caption\":\"Fondazione Giangiacomo Feltrinelli\"},\"image\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FondazioneFeltrinelli\",\"https:\\\/\\\/x.com\\\/FondFeltrinelli\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqUC9dAHm8G3edg2GPEoNow\",\"https:\\\/\\\/www.instagram.com\\\/fondazionefeltrinelli\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company-beta\\\/9183434\\\/?pathWildcard=9183434\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fondazione Giangiacomo Feltrinelli","description":"Fondazione Giangiacomo Feltrinelli is one of the most important european research and culture centers in history, politics, economy and more","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondazionefeltrinelli.it\/en\/","og_locale":"en_US","og_type":"article","og_title":"Fondazione Giangiacomo Feltrinelli","og_description":"Fondazione Giangiacomo Feltrinelli is one of the most important european research and culture centers in history, politics, economy and more","og_url":"https:\/\/fondazionefeltrinelli.it\/en\/","og_site_name":"Fondazione Giangiacomo Feltrinelli","article_publisher":"https:\/\/www.facebook.com\/FondazioneFeltrinelli","article_modified_time":"2024-09-19T09:18:43+00:00","og_image":[{"width":632,"height":552,"url":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/05\/Logo-Fondazione-Feltrinelli-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@FondFeltrinelli","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fondazionefeltrinelli.it\/en\/","url":"https:\/\/fondazionefeltrinelli.it\/en\/","name":"Fondazione Giangiacomo Feltrinelli","isPartOf":{"@id":"https:\/\/fondazionefeltrinelli.it\/#website"},"datePublished":"2023-05-04T11:48:52+00:00","dateModified":"2024-09-19T09:18:43+00:00","description":"Fondazione Giangiacomo Feltrinelli is one of the most important european research and culture centers in history, politics, economy and more","breadcrumb":{"@id":"https:\/\/fondazionefeltrinelli.it\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondazionefeltrinelli.it\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fondazionefeltrinelli.it\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fondazionefeltrinelli.it\/en\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/fondazionefeltrinelli.it\/#website","url":"https:\/\/fondazionefeltrinelli.it\/","name":"Fondazione Giangiacomo Feltrinelli","description":"","publisher":{"@id":"https:\/\/fondazionefeltrinelli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondazionefeltrinelli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fondazionefeltrinelli.it\/#organization","name":"Fondazione Giangiacomo Feltrinelli","url":"https:\/\/fondazionefeltrinelli.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fondazionefeltrinelli.it\/#\/schema\/logo\/image\/","url":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/05\/Logo-Fondazione-Feltrinelli-2.jpg","contentUrl":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/05\/Logo-Fondazione-Feltrinelli-2.jpg","width":632,"height":552,"caption":"Fondazione Giangiacomo Feltrinelli"},"image":{"@id":"https:\/\/fondazionefeltrinelli.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FondazioneFeltrinelli","https:\/\/x.com\/FondFeltrinelli","https:\/\/www.youtube.com\/channel\/UCqUC9dAHm8G3edg2GPEoNow","https:\/\/www.instagram.com\/fondazionefeltrinelli\/","https:\/\/www.linkedin.com\/company-beta\/9183434\/?pathWildcard=9183434"]}]}},"_links":{"self":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/24126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/comments?post=24126"}],"version-history":[{"count":23,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/24126\/revisions"}],"predecessor-version":[{"id":35236,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/24126\/revisions\/35236"}],"wp:attachment":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/media?parent=24126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}