{"id":20336,"date":"2023-05-19T16:36:00","date_gmt":"2023-05-19T14:36:00","guid":{"rendered":"https:\/\/fondazionefeltrinelli.it\/pubblicazioni\/"},"modified":"2024-02-21T12:22:21","modified_gmt":"2024-02-21T11:22:21","slug":"publications","status":"publish","type":"page","link":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/","title":{"rendered":"Publications"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":10588,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-progetti.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20336","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Publications - Fondazione Giangiacomo Feltrinelli<\/title>\n<meta name=\"description\" content=\"Feltrinelli Foundation publications: paper and digital series to explore manuscripts and archival documents.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondazionefeltrinelli.it\/en\/publications\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Publications - Fondazione Giangiacomo Feltrinelli\" \/>\n<meta property=\"og:description\" content=\"Feltrinelli Foundation publications: paper and digital series to explore manuscripts and archival documents.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondazionefeltrinelli.it\/en\/publications\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Giangiacomo Feltrinelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FondazioneFeltrinelli\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T11:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/08\/Pubblicazioni-1-1024x501.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/08\/Pubblicazioni-1-scaled.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@FondFeltrinelli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/publications\\\/\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/publications\\\/\",\"name\":\"Publications - Fondazione Giangiacomo Feltrinelli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/publications\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/publications\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pubblicazioni-1-scaled.jpg\",\"datePublished\":\"2023-05-19T14:36:00+00:00\",\"dateModified\":\"2024-02-21T11:22:21+00:00\",\"description\":\"Feltrinelli Foundation publications: paper and digital series to explore manuscripts and archival documents.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/publications\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/publications\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/publications\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pubblicazioni-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pubblicazioni-1-scaled.jpg\",\"width\":2560,\"height\":1252,\"caption\":\"publications\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/publications\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publications\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#website\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/\",\"name\":\"Fondazione Giangiacomo Feltrinelli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#organization\",\"name\":\"Fondazione Giangiacomo Feltrinelli\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-Fondazione-Feltrinelli-2.jpg\",\"contentUrl\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-Fondazione-Feltrinelli-2.jpg\",\"width\":632,\"height\":552,\"caption\":\"Fondazione Giangiacomo Feltrinelli\"},\"image\":{\"@id\":\"https:\\\/\\\/fondazionefeltrinelli.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FondazioneFeltrinelli\",\"https:\\\/\\\/x.com\\\/FondFeltrinelli\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqUC9dAHm8G3edg2GPEoNow\",\"https:\\\/\\\/www.instagram.com\\\/fondazionefeltrinelli\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company-beta\\\/9183434\\\/?pathWildcard=9183434\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Publications - Fondazione Giangiacomo Feltrinelli","description":"Feltrinelli Foundation publications: paper and digital series to explore manuscripts and archival documents.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/","og_locale":"en_US","og_type":"article","og_title":"Publications - Fondazione Giangiacomo Feltrinelli","og_description":"Feltrinelli Foundation publications: paper and digital series to explore manuscripts and archival documents.","og_url":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/","og_site_name":"Fondazione Giangiacomo Feltrinelli","article_publisher":"https:\/\/www.facebook.com\/FondazioneFeltrinelli","article_modified_time":"2024-02-21T11:22:21+00:00","og_image":[{"url":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/08\/Pubblicazioni-1-1024x501.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/08\/Pubblicazioni-1-scaled.jpg","twitter_site":"@FondFeltrinelli","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/","url":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/","name":"Publications - Fondazione Giangiacomo Feltrinelli","isPartOf":{"@id":"https:\/\/fondazionefeltrinelli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/#primaryimage"},"image":{"@id":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/#primaryimage"},"thumbnailUrl":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/08\/Pubblicazioni-1-scaled.jpg","datePublished":"2023-05-19T14:36:00+00:00","dateModified":"2024-02-21T11:22:21+00:00","description":"Feltrinelli Foundation publications: paper and digital series to explore manuscripts and archival documents.","breadcrumb":{"@id":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondazionefeltrinelli.it\/en\/publications\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/#primaryimage","url":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/08\/Pubblicazioni-1-scaled.jpg","contentUrl":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/08\/Pubblicazioni-1-scaled.jpg","width":2560,"height":1252,"caption":"publications"},{"@type":"BreadcrumbList","@id":"https:\/\/fondazionefeltrinelli.it\/en\/publications\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fondazionefeltrinelli.it\/en\/"},{"@type":"ListItem","position":2,"name":"Publications"}]},{"@type":"WebSite","@id":"https:\/\/fondazionefeltrinelli.it\/#website","url":"https:\/\/fondazionefeltrinelli.it\/","name":"Fondazione Giangiacomo Feltrinelli","description":"","publisher":{"@id":"https:\/\/fondazionefeltrinelli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondazionefeltrinelli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fondazionefeltrinelli.it\/#organization","name":"Fondazione Giangiacomo Feltrinelli","url":"https:\/\/fondazionefeltrinelli.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fondazionefeltrinelli.it\/#\/schema\/logo\/image\/","url":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/05\/Logo-Fondazione-Feltrinelli-2.jpg","contentUrl":"https:\/\/fondazionefeltrinelli.it\/wp-content\/uploads\/2023\/05\/Logo-Fondazione-Feltrinelli-2.jpg","width":632,"height":552,"caption":"Fondazione Giangiacomo Feltrinelli"},"image":{"@id":"https:\/\/fondazionefeltrinelli.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FondazioneFeltrinelli","https:\/\/x.com\/FondFeltrinelli","https:\/\/www.youtube.com\/channel\/UCqUC9dAHm8G3edg2GPEoNow","https:\/\/www.instagram.com\/fondazionefeltrinelli\/","https:\/\/www.linkedin.com\/company-beta\/9183434\/?pathWildcard=9183434"]}]}},"_links":{"self":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/20336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/comments?post=20336"}],"version-history":[{"count":2,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/20336\/revisions"}],"predecessor-version":[{"id":20338,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/pages\/20336\/revisions\/20338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/media\/10588"}],"wp:attachment":[{"href":"https:\/\/fondazionefeltrinelli.it\/en\/wp-json\/wp\/v2\/media?parent=20336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}